{"id":32015,"date":"2021-07-20T11:02:11","date_gmt":"2021-07-20T15:02:11","guid":{"rendered":"https:\/\/hortcouncil.ca\/?p=32015"},"modified":"2021-07-20T11:02:11","modified_gmt":"2021-07-20T15:02:11","slug":"etablissement-dun-code-de-conduite-des-distributeurs-detaillants-au-canada","status":"publish","type":"post","link":"https:\/\/fvgc.ca\/fr\/2021\/07\/20\/etablissement-dun-code-de-conduite-des-distributeurs-detaillants-au-canada\/","title":{"rendered":"\u00c9tablissement d&#8217;un code de conduite des distributeurs\/d\u00e9taillants au Canada"},"content":{"rendered":"<p><strong>Le 20 juillet 2021 &#8211;<\/strong> \u00c0 la suite de la r\u00e9union f\u00e9d\u00e9rale-provinciale-territoriale (FPT) des ministres de l&#8217;Agriculture du Canada la semaine derni\u00e8re, le Conseil canadien de l&#8217;horticulture (CCH) exprime son soutien \u00e0 l&#8217;\u00e9tablissement d&#8217;un code de conduite des distributeurs\/d\u00e9taillants au Canada en fonction d&#8217;une approche qui vise \u00e0 rendre plus \u00e9quitables les pratiques de vente au d\u00e9tail des aliments. La n\u00e9cessit\u00e9 d&#8217;un tel document a \u00e9t\u00e9 r\u00e9affirm\u00e9e au cours de la r\u00e9union de la semaine derni\u00e8re, de m\u00eame que les plans pour faire avancer le cadre.<\/p>\n<p>\u00ab Au nom des producteurs de fruits et l\u00e9gumes du Canada, nous sommes tr\u00e8s reconnaissants aux ministres de l&#8217;Agriculture du Canada d&#8217;avoir reconnu l&#8217;importance de cette question pour notre secteur \u00bb, a d\u00e9clar\u00e9 Rebecca Lee, directrice g\u00e9n\u00e9rale du CCH. \u00ab L&#8217;absence de pratiques \u00e9tablies dans ce domaine cr\u00e9e de nombreux d\u00e9fis pour nos producteurs et pose des complexit\u00e9s aux producteurs primaires, et le fait d&#8217;avoir une voie \u00e0 suivre d\u00e9finie par le gouvernement est une \u00e9tape productive. \u00bb<\/p>\n<p>Les conclusions du groupe de travail FPT sur les frais de vente au d\u00e9tail confirment que de nombreux producteurs connaissent des conditions incertaines sur le march\u00e9.<\/p>\n<p>Plus pr\u00e9cis\u00e9ment, le rapport a mis en \u00e9vidence les points suivants :<\/p>\n\n\n<p>&nbsp;<\/p>\n<p>Le CCH se r\u00e9jouit de l&#8217;engagement continu avec les partenaires de l&#8217;industrie pour \u00e9laborer le cadre visant \u00e0 d\u00e9crire les pistes potentielles de solutions. Tout au long de ce processus, les voix et les priorit\u00e9s des producteurs primaires &#8211; dont beaucoup sont de petites et moyennes entreprises &#8211; doivent \u00eatre activement pr\u00e9sentes \u00e0 la table pour assurer une repr\u00e9sentation \u00e9quitable.<\/p>\n<p>Pour de plus amples informations :<\/p>\n<strong>Jordan Boswell<\/strong><br \/>\nGestionnaire int\u00e9rimaire, d\u00e9veloppement et recherche strat\u00e9gique<br \/>\nConseil canadien de l&#8217;horticulture<br \/>\n<a href=\"mailto:jboswell@hortcouncil.ca\">jboswell@hortcouncil.ca<\/a>","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[23],"tags":[],"class_list":["post-32015","post","type-post","status-publish","format-standard","hentry","category-actualites"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00c9tablissement d&#039;un code de conduite des distributeurs\/d\u00e9taillants au Canada - FVGC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fvgc.ca\/fr\/2021\/07\/20\/etablissement-dun-code-de-conduite-des-distributeurs-detaillants-au-canada\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9tablissement d&#039;un code de conduite des distributeurs\/d\u00e9taillants au Canada - FVGC\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fvgc.ca\/fr\/2021\/07\/20\/etablissement-dun-code-de-conduite-des-distributeurs-detaillants-au-canada\/\" \/>\n<meta property=\"og:site_name\" content=\"FVGC\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-20T15:02:11+00:00\" \/>\n<meta name=\"author\" content=\"Ashley Peyrard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ashley Peyrard\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fvgc.ca\\\/en\\\/2021\\\/07\\\/20\\\/etablissement-dun-code-de-conduite-des-distributeurs-detaillants-au-canada\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fvgc.ca\\\/en\\\/2021\\\/07\\\/20\\\/etablissement-dun-code-de-conduite-des-distributeurs-detaillants-au-canada\\\/\"},\"author\":{\"name\":\"Ashley Peyrard\",\"@id\":\"https:\\\/\\\/fvgc.ca\\\/#\\\/schema\\\/person\\\/5d5ec6451ef7dc9293fb481d46af0c11\"},\"headline\":\"\u00c9tablissement d&#8217;un code de conduite des distributeurs\\\/d\u00e9taillants au Canada\",\"datePublished\":\"2021-07-20T15:02:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fvgc.ca\\\/en\\\/2021\\\/07\\\/20\\\/etablissement-dun-code-de-conduite-des-distributeurs-detaillants-au-canada\\\/\"},\"wordCount\":329,\"articleSection\":[\"Actualit\u00e9s\"],\"inLanguage\":\"fr-CA\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fvgc.ca\\\/en\\\/2021\\\/07\\\/20\\\/etablissement-dun-code-de-conduite-des-distributeurs-detaillants-au-canada\\\/\",\"url\":\"https:\\\/\\\/fvgc.ca\\\/en\\\/2021\\\/07\\\/20\\\/etablissement-dun-code-de-conduite-des-distributeurs-detaillants-au-canada\\\/\",\"name\":\"\u00c9tablissement d'un code de conduite des distributeurs\\\/d\u00e9taillants au Canada - FVGC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fvgc.ca\\\/#website\"},\"datePublished\":\"2021-07-20T15:02:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/fvgc.ca\\\/#\\\/schema\\\/person\\\/5d5ec6451ef7dc9293fb481d46af0c11\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fvgc.ca\\\/en\\\/2021\\\/07\\\/20\\\/etablissement-dun-code-de-conduite-des-distributeurs-detaillants-au-canada\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fvgc.ca\\\/en\\\/2021\\\/07\\\/20\\\/etablissement-dun-code-de-conduite-des-distributeurs-detaillants-au-canada\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fvgc.ca\\\/en\\\/2021\\\/07\\\/20\\\/etablissement-dun-code-de-conduite-des-distributeurs-detaillants-au-canada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fvgc.ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9tablissement d&#8217;un code de conduite des distributeurs\\\/d\u00e9taillants au Canada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fvgc.ca\\\/#website\",\"url\":\"https:\\\/\\\/fvgc.ca\\\/\",\"name\":\"FVGC\",\"description\":\"Representing Growers Across the Country\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fvgc.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fvgc.ca\\\/#\\\/schema\\\/person\\\/5d5ec6451ef7dc9293fb481d46af0c11\",\"name\":\"Ashley Peyrard\",\"url\":\"https:\\\/\\\/fvgc.ca\\\/fr\\\/author\\\/fruit-and-vegetable-growers-of-canada\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c9tablissement d'un code de conduite des distributeurs\/d\u00e9taillants au Canada - FVGC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fvgc.ca\/fr\/2021\/07\/20\/etablissement-dun-code-de-conduite-des-distributeurs-detaillants-au-canada\/","og_locale":"fr_CA","og_type":"article","og_title":"\u00c9tablissement d'un code de conduite des distributeurs\/d\u00e9taillants au Canada - FVGC","og_url":"https:\/\/fvgc.ca\/fr\/2021\/07\/20\/etablissement-dun-code-de-conduite-des-distributeurs-detaillants-au-canada\/","og_site_name":"FVGC","article_published_time":"2021-07-20T15:02:11+00:00","author":"Ashley Peyrard","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Ashley Peyrard","Estimation du temps de lecture":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fvgc.ca\/en\/2021\/07\/20\/etablissement-dun-code-de-conduite-des-distributeurs-detaillants-au-canada\/#article","isPartOf":{"@id":"https:\/\/fvgc.ca\/en\/2021\/07\/20\/etablissement-dun-code-de-conduite-des-distributeurs-detaillants-au-canada\/"},"author":{"name":"Ashley Peyrard","@id":"https:\/\/fvgc.ca\/#\/schema\/person\/5d5ec6451ef7dc9293fb481d46af0c11"},"headline":"\u00c9tablissement d&#8217;un code de conduite des distributeurs\/d\u00e9taillants au Canada","datePublished":"2021-07-20T15:02:11+00:00","mainEntityOfPage":{"@id":"https:\/\/fvgc.ca\/en\/2021\/07\/20\/etablissement-dun-code-de-conduite-des-distributeurs-detaillants-au-canada\/"},"wordCount":329,"articleSection":["Actualit\u00e9s"],"inLanguage":"fr-CA"},{"@type":"WebPage","@id":"https:\/\/fvgc.ca\/en\/2021\/07\/20\/etablissement-dun-code-de-conduite-des-distributeurs-detaillants-au-canada\/","url":"https:\/\/fvgc.ca\/en\/2021\/07\/20\/etablissement-dun-code-de-conduite-des-distributeurs-detaillants-au-canada\/","name":"\u00c9tablissement d'un code de conduite des distributeurs\/d\u00e9taillants au Canada - FVGC","isPartOf":{"@id":"https:\/\/fvgc.ca\/#website"},"datePublished":"2021-07-20T15:02:11+00:00","author":{"@id":"https:\/\/fvgc.ca\/#\/schema\/person\/5d5ec6451ef7dc9293fb481d46af0c11"},"breadcrumb":{"@id":"https:\/\/fvgc.ca\/en\/2021\/07\/20\/etablissement-dun-code-de-conduite-des-distributeurs-detaillants-au-canada\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fvgc.ca\/en\/2021\/07\/20\/etablissement-dun-code-de-conduite-des-distributeurs-detaillants-au-canada\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/fvgc.ca\/en\/2021\/07\/20\/etablissement-dun-code-de-conduite-des-distributeurs-detaillants-au-canada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fvgc.ca\/"},{"@type":"ListItem","position":2,"name":"\u00c9tablissement d&#8217;un code de conduite des distributeurs\/d\u00e9taillants au Canada"}]},{"@type":"WebSite","@id":"https:\/\/fvgc.ca\/#website","url":"https:\/\/fvgc.ca\/","name":"FVGC","description":"Representing Growers Across the Country","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fvgc.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Person","@id":"https:\/\/fvgc.ca\/#\/schema\/person\/5d5ec6451ef7dc9293fb481d46af0c11","name":"Ashley Peyrard","url":"https:\/\/fvgc.ca\/fr\/author\/fruit-and-vegetable-growers-of-canada\/"}]}},"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/fvgc.ca\/fr\/wp-json\/wp\/v2\/posts\/32015","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fvgc.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fvgc.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fvgc.ca\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/fvgc.ca\/fr\/wp-json\/wp\/v2\/comments?post=32015"}],"version-history":[{"count":0,"href":"https:\/\/fvgc.ca\/fr\/wp-json\/wp\/v2\/posts\/32015\/revisions"}],"wp:attachment":[{"href":"https:\/\/fvgc.ca\/fr\/wp-json\/wp\/v2\/media?parent=32015"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fvgc.ca\/fr\/wp-json\/wp\/v2\/categories?post=32015"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fvgc.ca\/fr\/wp-json\/wp\/v2\/tags?post=32015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}