{"id":3162,"date":"2017-04-10T07:30:02","date_gmt":"2017-04-10T11:30:02","guid":{"rendered":"https:\/\/www.hortcouncil.ca\/?p=3162"},"modified":"2024-09-18T16:01:18","modified_gmt":"2024-09-18T20:01:18","slug":"exploiter-le-potentiel-des-drones-pour-maintenir-le-positionnement-concurrentiel-de-ses-cultures","status":"publish","type":"post","link":"https:\/\/fvgc.ca\/fr\/2017\/04\/10\/exploiter-le-potentiel-des-drones-pour-maintenir-le-positionnement-concurrentiel-de-ses-cultures\/","title":{"rendered":"Exploiter le potentiel des drones pour maintenir le positionnement concurrentiel de ses cultures"},"content":{"rendered":"<p>L\u2019industrie agricole a toujours beaucoup mis\u00e9 sur l\u2019innovation pour se d\u00e9velopper. Alors que les v\u00e9hicules a\u00e9riens sans pilote (UAV) sont de plus en plus r\u00e9pandus partout en Am\u00e9rique du Nord, des agronomes tourn\u00e9s vers l\u2019avenir ont recours \u00e0 cette nouvelle technologie a\u00e9roport\u00e9e pour survoler leurs cultures afin d\u2019accro\u00eetre leur productivit\u00e9 sur terre. Certains croient que la technologie peut leur donner un net avantage sur la concurrence, mais elle peut s\u2019av\u00e9rer co\u00fbteuse.<\/p>\n<p>Heureusement, un nombre croissant d\u2019outils pratiques et plus abordables commencent \u00e0 faire leur apparition. Autrefois strictement r\u00e9serv\u00e9s \u00e0 un usage militaire, les UAV et les drones sont les tout derniers outils qu\u2019ont adopt\u00e9s les agriculteurs pour faire un meilleur suivi de l\u2019\u00e9tat de leurs cultures. Gr\u00e2ce \u00e0 leur point de vue a\u00e9rien, ces dispositifs leur permettent de voir l\u2019\u00e9tat de leurs champs pendant la saison de croissance, ce qui peut potentiellement faire augmenter la marge de profit de leur entreprise. Loin des mod\u00e8les de drones ordinaires propos\u00e9s au grand public, les UAV actuellement utilis\u00e9s dans l\u2019industrie agricole sont des engins a\u00e9riens haut de gamme \u00e0 la fine pointe de la technologie qui permettent de recueillir des renseignements. Le prix d\u2019un drone varie g\u00e9n\u00e9ralement selon les besoins des producteurs. Leur faut-il un engin \u00e0 voilure fixe ou un quadricopt\u00e8re? Un drone automatis\u00e9 ou command\u00e9? Quelle qualit\u00e9 d\u2019image recherchent-ils? Bref, les r\u00e9ponses \u00e0 ces questions, ainsi que bien d\u2019autres facteurs, auront \u00e9videmment une incidence sur le prix \u00e0 payer.<\/p>\n<p>Les UAV proposent une vue a\u00e9rienne \u00e0 faible altitude, en survolant de quelques m\u00e8tres la v\u00e9g\u00e9tation jusqu\u2019\u00e0 un plafond d\u2019environ 120 m\u00e8tres, sans causer de dommage aux terres. Les drones offrent un point de vue des champs que la plupart des producteurs ne pourraient obtenir autrement, \u00e0 moins d\u2019avoir acc\u00e8s \u00e0 des avions pilot\u00e9s ou de pouvoir recueillir des images par satellite. Bien que les satellites fournissent des images d\u2019une qualit\u00e9 exceptionnelle, les drones peuvent capter en temps r\u00e9el des images des cultures en couleur naturelle ou multispectrales, d\u2019une qualit\u00e9 \u00e9gale ou semblable, pour une fraction du co\u00fbt. L\u2019une des utilisations du drone les plus r\u00e9pandues en agriculture est l\u2019\u00e9pandage d\u2019engrais \u00e0 taux variable : le drone r\u00e9alise une cartographie des champs en tenant compte de l\u2019indice de biomasse. Puis, une carte sur laquelle sont indiqu\u00e9es les t\u00e2ches \u00e0 accomplir est alors \u00e9tablie pour le v\u00e9hicule employ\u00e9, qui proc\u00e8de ensuite \u00e0 l\u2019\u00e9pandage.<\/p>\n Photographer: Knoell Marketing\n<p>\u00ab Le drone peut donc localiser les parcelles qui devraient recevoir une dose plus importante d\u2019engrais, l\u00e0 o\u00f9 le potentiel de rendement est sup\u00e9rieur et les plants peuvent en b\u00e9n\u00e9ficier, ce qui \u00e9vite d\u2019en \u00e9pandre inutilement dans tout le champ. Les co\u00fbts associ\u00e9s et l\u2019impact environnemental en sont ainsi diminu\u00e9s \u00bb, a expliqu\u00e9 M. Joris IJsselmuiden (Ph. D.), chercheur dans le domaine de la robotique et de l\u2019automatisation agricoles au sein du groupe de recherche sur les technologies agricoles de l\u2019Universit\u00e9 et du campus de recherche de Wageningen aux Pays-Bas.<\/p>\n<p>\u00ab Il est facile de voir comment le drone, avec ses atouts, pr\u00e9sente un potentiel \u00e9norme pour cet usage. \u00bb Malgr\u00e9 les avantages et la popularit\u00e9 grandissante des drones, leur utilisation peut poser certaines difficult\u00e9s. M\u00eame s\u2019ils sont de plus en plus perfectionn\u00e9s, les drones ont certaines limites : leur batterie a une autonomie relativement faible et leur charge utile est limit\u00e9e, notamment. En outre, le bon fonctionnement d\u2019un v\u00e9hicule a\u00e9rien sans pilote est grandement tributaire des conditions m\u00e9t\u00e9orologiques. En effet, puisqu\u2019il peut seulement capter des images de qualit\u00e9 lorsque le ciel est d\u00e9gag\u00e9, la pr\u00e9sence d\u2019ombres caus\u00e9es par une couverture nuageuse donnerait un clich\u00e9 \u00e0 l\u2019utilit\u00e9 limit\u00e9e. Bien que les drones puissent contribuer \u00e0 faciliter la surveillance d\u2019un champ, les activit\u00e9s comme la programmation et le pilotage d\u2019un drone, la prise d\u2019images et le traitement des images sont chronophages.<\/p>\n<blockquote><p>Le monde \u00e9volue et la soci\u00e9t\u00e9 \u00e9galement [&#8230;]. Si vous, en tant que propri\u00e9taire d\u2019entreprise, refusez de changer, on vous remplacera.<\/p><\/blockquote>\n<p>En outre, la prise de d\u00e9cisions sur la base des images capt\u00e9es par l\u2019UAV peut prendre encore des heures, voire des jours. En fin de compte, les drones ne sont qu\u2019un outil de suppl\u00e9mentaire, et ils ne remplaceront pas la pr\u00e9sence physique du producteur sur ses terres.<\/p>\n<p>\u00ab Les producteurs qui exploitent le potentiel d\u2019imagerie des drones peuvent plus facilement localiser les parcelles suspectes de leurs champs. Ainsi, ils sont en mesure de se rendre directement sur place pour voir ce qui se passe avec leurs cultures, explique Terence Hochstein, directeur g\u00e9n\u00e9ral des producteurs de pommes de terre de l\u2019Alberta. Un drone peut acc\u00e9l\u00e9rer les choses, mais le producteur devra encore enfiler ses bottes et se salir pour aller constater par lui-m\u00eame l\u2019\u00e9tat de la situation. \u00bb<\/p>\n<p>Il n\u2019en demeure pas moins que les producteurs qui refusent d\u2019envisager la possibilit\u00e9 d\u2019utiliser les UAV pour leurs affaires s\u2019exposent \u00e0 un risque. Comme les drones sont de plus en plus accessibles et qu\u2019ils pr\u00e9sentent un nombre croissant d\u2019applications concr\u00e8tes, la pr\u00e9sence de ces engins bourdonnants au-dessus des champs deviendra chose courante. Comme c\u2019est le cas avec toutes les avanc\u00e9es technologiques au sein du secteur de l\u2019horticulture, les adopteurs pr\u00e9coces seront port\u00e9s \u00e0 demeurer \u00e0 l\u2019avant-garde, tandis que ceux qui ne voudront pas s\u2019adapter prendront du retard.<\/p>\n<p>\u00ab Le monde \u00e9volue et la soci\u00e9t\u00e9 \u00e9galement, a indiqu\u00e9 M. IJsselmuiden. Sachez que des entreprises comme John Deere et Lely concentrent d\u00e9sormais leur offre autant sur l\u2019analyse de donn\u00e9es que sur la vente d\u2019\u00e9quipement (ou le feront bient\u00f4t, si ce n\u2019est pas encore le cas). Si vous, en tant que propri\u00e9taire d\u2019entreprise, refusez de changer, on vous remplacera. \u00bb On recommande aux producteurs qui souhaitent faire l\u2019acquisition d\u2019un drone pour survoler leurs champs de communiquer d\u2019abord avec des pairs qui s\u2019en servent d\u00e9j\u00e0, de v\u00e9rifier les lois qui s\u2019appliquent sur leur territoire et de d\u00e9terminer \u00e0 quelles fins sera utilis\u00e9 leur drone. Le producteur souhaite-t-il simplement obtenir une repr\u00e9sentation de ses cultures telles qu\u2019elles sont? Veut-il diffuser sur YouTube une vid\u00e9o sensationnelle \u00e0 des fins promotionnelles?<\/p>\n<p>Cherche-t-il \u00e0 obtenir des images g\u00e9or\u00e9f\u00e9renc\u00e9es de grande qualit\u00e9 dont il pourra se servir pour am\u00e9liorer ses syst\u00e8mes de culture? Un seul drone sera-t-il suffisant pour faire le travail de mani\u00e8re efficace ou la superficie cultiv\u00e9e est-elle si importante qu\u2019elle n\u00e9cessitera plusieurs drones? Les producteurs devraient \u00e9galement savoir que de nombreuses entreprises sp\u00e9cialis\u00e9es offrant des services de drone existent d\u00e9j\u00e0 et qu\u2019ils n\u2019ont pas n\u00e9cessairement \u00e0 investir une somme consid\u00e9rable dans l\u2019achat d\u2019un drone.<\/p>\n<p>En proc\u00e9dant ainsi, les producteurs pourraient enregistrer un meilleur b\u00e9n\u00e9fice net. \u00ab Bien que l\u2019agriculteur puisse exprimer le d\u00e9sir de poss\u00e9der son propre drone, il peut s\u2019av\u00e9rer plus pratique et rentable d\u2019avoir recours aux services d\u2019UAV offerts par une soci\u00e9t\u00e9 d\u2019experts-conseils \u00bb, indique Darren White de Delta Ag Services, un cabinet-conseil en cultures ind\u00e9pendant du Manitoba. \u00ab De cette mani\u00e8re, l\u2019agriculteur peut voir si les images capt\u00e9es pr\u00e9sentent une r\u00e9elle utilit\u00e9 pour son entreprise. \u00bb<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019industrie agricole a toujours beaucoup mis\u00e9 sur l\u2019innovation pour se d\u00e9velopper. Alors que les v\u00e9hicules a\u00e9riens sans pilote (UAV) sont de plus en plus r\u00e9pandus partout en Am\u00e9rique du Nord, des agronomes tourn\u00e9s vers l\u2019avenir ont recours \u00e0 cette nouvelle technologie a\u00e9roport\u00e9e pour survoler leurs cultures afin d\u2019accro\u00eetre leur productivit\u00e9 sur terre. Certains croient que [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":3157,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[29],"tags":[],"class_list":["post-3162","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dossiers-de-lheure"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Exploiter le potentiel des drones pour maintenir le positionnement concurrentiel de ses cultures - FVGC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fvgc.ca\/fr\/2017\/04\/10\/exploiter-le-potentiel-des-drones-pour-maintenir-le-positionnement-concurrentiel-de-ses-cultures\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Exploiter le potentiel des drones pour maintenir le positionnement concurrentiel de ses cultures - FVGC\" \/>\n<meta property=\"og:description\" content=\"L\u2019industrie agricole a toujours beaucoup mis\u00e9 sur l\u2019innovation pour se d\u00e9velopper. Alors que les v\u00e9hicules a\u00e9riens sans pilote (UAV) sont de plus en plus r\u00e9pandus partout en Am\u00e9rique du Nord, des agronomes tourn\u00e9s vers l\u2019avenir ont recours \u00e0 cette nouvelle technologie a\u00e9roport\u00e9e pour survoler leurs cultures afin d\u2019accro\u00eetre leur productivit\u00e9 sur terre. Certains croient que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fvgc.ca\/fr\/2017\/04\/10\/exploiter-le-potentiel-des-drones-pour-maintenir-le-positionnement-concurrentiel-de-ses-cultures\/\" \/>\n<meta property=\"og:site_name\" content=\"FVGC\" \/>\n<meta property=\"article:published_time\" content=\"2017-04-10T11:30:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-18T20:01:18+00:00\" \/>\n<meta name=\"author\" content=\"Ashley Peyrard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ashley Peyrard\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fvgc.ca\\\/2017\\\/04\\\/10\\\/exploiter-le-potentiel-des-drones-pour-maintenir-le-positionnement-concurrentiel-de-ses-cultures\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fvgc.ca\\\/2017\\\/04\\\/10\\\/exploiter-le-potentiel-des-drones-pour-maintenir-le-positionnement-concurrentiel-de-ses-cultures\\\/\"},\"author\":{\"name\":\"Ashley Peyrard\",\"@id\":\"https:\\\/\\\/fvgc.ca\\\/#\\\/schema\\\/person\\\/5d5ec6451ef7dc9293fb481d46af0c11\"},\"headline\":\"Exploiter le potentiel des drones pour maintenir le positionnement concurrentiel de ses cultures\",\"datePublished\":\"2017-04-10T11:30:02+00:00\",\"dateModified\":\"2024-09-18T20:01:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fvgc.ca\\\/2017\\\/04\\\/10\\\/exploiter-le-potentiel-des-drones-pour-maintenir-le-positionnement-concurrentiel-de-ses-cultures\\\/\"},\"wordCount\":1300,\"image\":{\"@id\":\"https:\\\/\\\/fvgc.ca\\\/2017\\\/04\\\/10\\\/exploiter-le-potentiel-des-drones-pour-maintenir-le-positionnement-concurrentiel-de-ses-cultures\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Dossiers de l'heure\"],\"inLanguage\":\"fr-CA\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fvgc.ca\\\/2017\\\/04\\\/10\\\/exploiter-le-potentiel-des-drones-pour-maintenir-le-positionnement-concurrentiel-de-ses-cultures\\\/\",\"url\":\"https:\\\/\\\/fvgc.ca\\\/2017\\\/04\\\/10\\\/exploiter-le-potentiel-des-drones-pour-maintenir-le-positionnement-concurrentiel-de-ses-cultures\\\/\",\"name\":\"Exploiter le potentiel des drones pour maintenir le positionnement concurrentiel de ses cultures - FVGC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fvgc.ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fvgc.ca\\\/2017\\\/04\\\/10\\\/exploiter-le-potentiel-des-drones-pour-maintenir-le-positionnement-concurrentiel-de-ses-cultures\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fvgc.ca\\\/2017\\\/04\\\/10\\\/exploiter-le-potentiel-des-drones-pour-maintenir-le-positionnement-concurrentiel-de-ses-cultures\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2017-04-10T11:30:02+00:00\",\"dateModified\":\"2024-09-18T20:01:18+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/fvgc.ca\\\/#\\\/schema\\\/person\\\/5d5ec6451ef7dc9293fb481d46af0c11\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fvgc.ca\\\/2017\\\/04\\\/10\\\/exploiter-le-potentiel-des-drones-pour-maintenir-le-positionnement-concurrentiel-de-ses-cultures\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fvgc.ca\\\/2017\\\/04\\\/10\\\/exploiter-le-potentiel-des-drones-pour-maintenir-le-positionnement-concurrentiel-de-ses-cultures\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/fvgc.ca\\\/2017\\\/04\\\/10\\\/exploiter-le-potentiel-des-drones-pour-maintenir-le-positionnement-concurrentiel-de-ses-cultures\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fvgc.ca\\\/2017\\\/04\\\/10\\\/exploiter-le-potentiel-des-drones-pour-maintenir-le-positionnement-concurrentiel-de-ses-cultures\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fvgc.ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Exploiter le potentiel des drones pour maintenir le positionnement concurrentiel de ses cultures\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fvgc.ca\\\/#website\",\"url\":\"https:\\\/\\\/fvgc.ca\\\/\",\"name\":\"FVGC\",\"description\":\"Representing Growers Across the Country\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fvgc.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fvgc.ca\\\/#\\\/schema\\\/person\\\/5d5ec6451ef7dc9293fb481d46af0c11\",\"name\":\"Ashley Peyrard\",\"url\":\"https:\\\/\\\/fvgc.ca\\\/fr\\\/author\\\/fruit-and-vegetable-growers-of-canada\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Exploiter le potentiel des drones pour maintenir le positionnement concurrentiel de ses cultures - FVGC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fvgc.ca\/fr\/2017\/04\/10\/exploiter-le-potentiel-des-drones-pour-maintenir-le-positionnement-concurrentiel-de-ses-cultures\/","og_locale":"fr_CA","og_type":"article","og_title":"Exploiter le potentiel des drones pour maintenir le positionnement concurrentiel de ses cultures - FVGC","og_description":"L\u2019industrie agricole a toujours beaucoup mis\u00e9 sur l\u2019innovation pour se d\u00e9velopper. Alors que les v\u00e9hicules a\u00e9riens sans pilote (UAV) sont de plus en plus r\u00e9pandus partout en Am\u00e9rique du Nord, des agronomes tourn\u00e9s vers l\u2019avenir ont recours \u00e0 cette nouvelle technologie a\u00e9roport\u00e9e pour survoler leurs cultures afin d\u2019accro\u00eetre leur productivit\u00e9 sur terre. Certains croient que [&hellip;]","og_url":"https:\/\/fvgc.ca\/fr\/2017\/04\/10\/exploiter-le-potentiel-des-drones-pour-maintenir-le-positionnement-concurrentiel-de-ses-cultures\/","og_site_name":"FVGC","article_published_time":"2017-04-10T11:30:02+00:00","article_modified_time":"2024-09-18T20:01:18+00:00","author":"Ashley Peyrard","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Ashley Peyrard","Estimation du temps de lecture":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fvgc.ca\/2017\/04\/10\/exploiter-le-potentiel-des-drones-pour-maintenir-le-positionnement-concurrentiel-de-ses-cultures\/#article","isPartOf":{"@id":"https:\/\/fvgc.ca\/2017\/04\/10\/exploiter-le-potentiel-des-drones-pour-maintenir-le-positionnement-concurrentiel-de-ses-cultures\/"},"author":{"name":"Ashley Peyrard","@id":"https:\/\/fvgc.ca\/#\/schema\/person\/5d5ec6451ef7dc9293fb481d46af0c11"},"headline":"Exploiter le potentiel des drones pour maintenir le positionnement concurrentiel de ses cultures","datePublished":"2017-04-10T11:30:02+00:00","dateModified":"2024-09-18T20:01:18+00:00","mainEntityOfPage":{"@id":"https:\/\/fvgc.ca\/2017\/04\/10\/exploiter-le-potentiel-des-drones-pour-maintenir-le-positionnement-concurrentiel-de-ses-cultures\/"},"wordCount":1300,"image":{"@id":"https:\/\/fvgc.ca\/2017\/04\/10\/exploiter-le-potentiel-des-drones-pour-maintenir-le-positionnement-concurrentiel-de-ses-cultures\/#primaryimage"},"thumbnailUrl":"","articleSection":["Dossiers de l'heure"],"inLanguage":"fr-CA"},{"@type":"WebPage","@id":"https:\/\/fvgc.ca\/2017\/04\/10\/exploiter-le-potentiel-des-drones-pour-maintenir-le-positionnement-concurrentiel-de-ses-cultures\/","url":"https:\/\/fvgc.ca\/2017\/04\/10\/exploiter-le-potentiel-des-drones-pour-maintenir-le-positionnement-concurrentiel-de-ses-cultures\/","name":"Exploiter le potentiel des drones pour maintenir le positionnement concurrentiel de ses cultures - FVGC","isPartOf":{"@id":"https:\/\/fvgc.ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fvgc.ca\/2017\/04\/10\/exploiter-le-potentiel-des-drones-pour-maintenir-le-positionnement-concurrentiel-de-ses-cultures\/#primaryimage"},"image":{"@id":"https:\/\/fvgc.ca\/2017\/04\/10\/exploiter-le-potentiel-des-drones-pour-maintenir-le-positionnement-concurrentiel-de-ses-cultures\/#primaryimage"},"thumbnailUrl":"","datePublished":"2017-04-10T11:30:02+00:00","dateModified":"2024-09-18T20:01:18+00:00","author":{"@id":"https:\/\/fvgc.ca\/#\/schema\/person\/5d5ec6451ef7dc9293fb481d46af0c11"},"breadcrumb":{"@id":"https:\/\/fvgc.ca\/2017\/04\/10\/exploiter-le-potentiel-des-drones-pour-maintenir-le-positionnement-concurrentiel-de-ses-cultures\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fvgc.ca\/2017\/04\/10\/exploiter-le-potentiel-des-drones-pour-maintenir-le-positionnement-concurrentiel-de-ses-cultures\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/fvgc.ca\/2017\/04\/10\/exploiter-le-potentiel-des-drones-pour-maintenir-le-positionnement-concurrentiel-de-ses-cultures\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/fvgc.ca\/2017\/04\/10\/exploiter-le-potentiel-des-drones-pour-maintenir-le-positionnement-concurrentiel-de-ses-cultures\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fvgc.ca\/"},{"@type":"ListItem","position":2,"name":"Exploiter le potentiel des drones pour maintenir le positionnement concurrentiel de ses cultures"}]},{"@type":"WebSite","@id":"https:\/\/fvgc.ca\/#website","url":"https:\/\/fvgc.ca\/","name":"FVGC","description":"Representing Growers Across the Country","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fvgc.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Person","@id":"https:\/\/fvgc.ca\/#\/schema\/person\/5d5ec6451ef7dc9293fb481d46af0c11","name":"Ashley Peyrard","url":"https:\/\/fvgc.ca\/fr\/author\/fruit-and-vegetable-growers-of-canada\/"}]}},"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/fvgc.ca\/fr\/wp-json\/wp\/v2\/posts\/3162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fvgc.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fvgc.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fvgc.ca\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/fvgc.ca\/fr\/wp-json\/wp\/v2\/comments?post=3162"}],"version-history":[{"count":0,"href":"https:\/\/fvgc.ca\/fr\/wp-json\/wp\/v2\/posts\/3162\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fvgc.ca\/fr\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/fvgc.ca\/fr\/wp-json\/wp\/v2\/media?parent=3162"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fvgc.ca\/fr\/wp-json\/wp\/v2\/categories?post=3162"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fvgc.ca\/fr\/wp-json\/wp\/v2\/tags?post=3162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}